{"id":158260,"date":"2024-01-08T11:53:03","date_gmt":"2024-01-08T10:53:03","guid":{"rendered":"https:\/\/www.batmagazine.it\/notizie\/?p=158260"},"modified":"2024-01-08T11:53:05","modified_gmt":"2024-01-08T10:53:05","slug":"calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola","status":"publish","type":"post","link":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/","title":{"rendered":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola"},"content":{"rendered":"\n<p>Un tris secco in esterna per inaugurare al meglio il nuovo anno e, al contempo, per preservare la leadership nel girone. Nella trasferta della terza di ritorno contro lo <strong>Spinazzola<\/strong>, domiciliato sul sintetico del \u201cVicino\u201d di Gravina, il <strong>Bisceglie Calcio<\/strong> riprende la propria corsa in vetta, dopo le festivit\u00e0, nel <strong>girone A del campionato di Eccellenza<\/strong>, collezionando il sesto successo consecutivo, il decimo nelle ultime 11 gare disputate.<\/p>\n\n\n\n<p>Non inganni, tuttavia, il rotondo punteggio maturato grazie agli acuti di due difensori (il centrale Lucero e il terzino Morisco) e del play Stefanini, poich\u00e9 per due terzi di gara l\u2019arcigno collettivo murgiano ha dato filo da torcere ai nerazzurri, abili a loro volta ad imporsi con una prestazione di carattere, sostanza e lucidit\u00e0 nei momenti clou della contesa.<\/p>\n\n\n\n<p>In avvio <strong>mister Di Meo<\/strong> deve rinunciare al convalescente Pignataro nonch\u00e9 agli influenzati Farucci e Mangialardi, rimpiazzati nei rispettivi ruoli da Marinelli e Petitti, con Kouame per la prima volta titolare dopo l\u2019infortunio e Lucero preferito a Rodriguez al centro della difesa in coppia con capitan Sanchez. <\/p>\n\n\n\n<p>La pioggia caduta prima del fischio iniziale rende ostico il compito dei protagonisti, costretti a cimentarsi su un sintetico oltremodo viscido e poco confacente allo sviluppo di trame lineari. Il primo timido tentativo del Bisceglie arriva al 7\u2019 con il destro fuori misura di Kouame, mentre al 21\u2019 il tiro-cross di Kone dal versante destro \u00e8 sventato con un po\u2019 di apprensione dalla difesa spinazzolese. <\/p>\n\n\n\n<p>Risultato schiodato al 23\u2019: in proiezione offensiva, Pablo Lucero incorna in area il piazzato dalle retrovie di Petitti indirizzandolo sulla sinistra dell\u2019incolpevole Liso per la gioia degli oltre 100 supporters stellati al seguito. I padroni di casa provano a replicare al 26\u2019 con il rasoterra di Perez bloccato a terra da Suma, quindi al 35\u2019 Bonicelli sfugge alla marcatura di Cappellari e apparecchia in mezzo per il compagno di reparto Di Rito, contrastato da Dinielli al momento della conclusione. <\/p>\n\n\n\n<p>A ridosso dell\u2019intervallo il Bisceglie rischia grosso in un paio di circostanze: al 44\u2019 la stoccata dal limite di Colonna sfiora il montante sinistro, poi nell\u2019unico minuto di recupero Suma \u00e8 provvidenziale nel respingere con un intervento felino il colpo di testa sottomisura dell\u2019ex Zaldua.<\/p>\n\n\n\n<p>Spinazzola agguerrito e pericoloso anche al rientro. Dopo 100\u201d Bonanno suggerisce per l\u2019inzuccata di Perez spentasi a lato, mentre al 9\u2019 la vol\u00e9e da buona posizione di Di Rito (encomiabile e prezioso nel lavoro \u201csporco\u201d dalla mediana in avanti) risulta alta. Un minuto pi\u00f9 tardi Colonna cestina un\u2019ottima chance nel cuore dell\u2019area nerazzurra, quindi al 14\u2019 il neo entrato Ngom imbecca il ben appostato Perez, la cui soluzione aerea si perde sulla sinistra della porta di Suma. <\/p>\n\n\n\n<p>Il cambio in mediana (Fucci in luogo di Kouame) precede il letale \u201cuno-due\u201d con cui il Bisceglie blinda il colpaccio. Al 20\u2019 Morisco intercetta palla sulla trequarti, s\u2019invola per vie centrali e quasi dal limite si produce in un portentoso mancino incastonatosi sotto l\u2019incrocio di sinistra per gli applausi a scena aperta di tutto lo stadio. <\/p>\n\n\n\n<p>Passano 4\u2019 allorch\u00e9 Kone si procura una punizione sul lato corto dell\u2019area, con Petitti bravo ad apparecchiare in mezzo per l\u2019elevazione vincente di Stefanini, in rete nel giorno del suo 33esimo compleanno. Curiosit\u00e0: per tutti e tre i marcatori di giornata si tratta del primo gol stagionale con la maglia nerazzurra. Verdetto in ghiaccio e poche emozioni fino al termine (esordio per Avantaggiato), con Suma puntuale in uscita bassa su Ngom (29\u2019) e Kone impreciso con uno shoot poderoso appena alto (36\u2019) dopo un\u2019avvolgente azione corale.<\/p>\n\n\n\n<p>Per la capolista distanze inalterate sulle inseguitrici Unione Calcio (+1) e Molfetta (+5). Intanto domenica prossima, nel primo appuntamento casalingo del 2024, \u00e8 in calendario la sfida al Borgorosso Molfetta.<\/p>\n\n\n\n<p><strong><em>Tabellino campionato di Eccellenza \u2013 3^ giornata di ritorno<\/em><\/strong><\/p>\n\n\n\n<p><strong>NUOVA SPINAZZOLA &#8211; BISCEGLIE 0-3<\/strong><\/p>\n\n\n\n<p><strong>SPINAZZOLA<\/strong>: Liso, Cappellari, Andrisani (41\u2019 st Basile), Dentamaro, Dinielli, Losappio, Perez (34\u2019 st Mazzilli), Colonna (22\u2019 st Ladogana), Zaldua, Romio (41\u2019 st Forenza), Bonanno (12\u2019 st Ngom). A disp. Sanza, Zingaro, Lobjanidze, Guacci. All. Di Meo.<\/p>\n\n\n\n<p><strong>BISCEGLIE<\/strong>: Suma, Marinelli, Morisco (43\u2019 st Napoli), Sanchez, Lucero, Kouame (15\u2019 st Fucci), Stefanini, Petitti (27\u2019 st Rodriguez), Di Rito (40\u2019 st Monaco), Bonicelli, Kone (41\u2019 st Avantaggiato). A disp. Zinfollino, Cassatella, Dembele, Losapio. All. Di Meo.<\/p>\n\n\n\n<p><strong>ARBITRO<\/strong>: Albione di Lecce.<\/p>\n\n\n\n<p><strong>ASSISTENTI<\/strong>: Alfieri e Sibilio.<\/p>\n\n\n\n<p><strong>RETI<\/strong>: pt 23\u2019 Lucero; st 20\u2019 Bonicelli, 23\u2019 Stefanini.<\/p>\n\n\n\n<p><strong>NOTE<\/strong>: angoli 3-0; rec. pt 1\u2019, st 3\u2019. <strong>AMMONITI<\/strong>: Lucero, Andrisani.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"158262\" src=\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-1024x682.jpg\" alt=\"\" class=\"wp-image-158262\" srcset=\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-1024x682.jpg 1024w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-300x200.jpg 300w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-768x512.jpg 768w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-1536x1024.jpg 1536w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-2048x1365.jpg 2048w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-696x464.jpg 696w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-1068x712.jpg 1068w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-gol-1-1920x1280.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"158263\" src=\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-1024x682.jpg\" alt=\"\" class=\"wp-image-158263\" srcset=\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-1024x682.jpg 1024w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-300x200.jpg 300w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-768x512.jpg 768w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-1536x1024.jpg 1536w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-2048x1365.jpg 2048w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-696x464.jpg 696w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-1068x712.jpg 1068w, https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/gioia-Lucero-1-1920x1280.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici<\/p>\n","protected":false},"author":2,"featured_media":158261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,2131,5],"tags":[28795,4444,17646,15920,26473,2100,26501,25953],"class_list":{"0":"post-158260","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bisceglie","8":"category-calcio","9":"category-sport","10":"tag-3-giornata-ritorno","11":"tag-bisceglie-calcio","12":"tag-eccellenza","13":"tag-girone-a","14":"tag-mister-di-meo","15":"tag-spinazzola","16":"tag-stadio-vicino","17":"tag-stagione-2023-2024"},"featured_image_url":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1-1024x682.jpg","primary_category":{"id":19,"name":"Bisceglie"},"author_name":"Redazione","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine<\/title>\n<meta name=\"description\" content=\"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine\" \/>\n<meta property=\"og:description\" content=\"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\" \/>\n<meta property=\"og:site_name\" content=\"BATmagazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BatMagazine\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T10:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-08T10:53:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/f25ee2762381b507b66ff3f592fb3a5c\"},\"headline\":\"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola\",\"datePublished\":\"2024-01-08T10:53:03+00:00\",\"dateModified\":\"2024-01-08T10:53:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\"},\"wordCount\":718,\"publisher\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg\",\"keywords\":[\"3^ giornata ritorno\",\"Bisceglie Calcio\",\"Eccellenza\",\"Girone A\",\"mister di meo\",\"spinazzola\",\"Stadio Vicino\",\"stagione 2023\/2024\"],\"articleSection\":[\"Bisceglie\",\"Calcio\",\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\",\"name\":\"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine\",\"isPartOf\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg\",\"datePublished\":\"2024-01-08T10:53:03+00:00\",\"dateModified\":\"2024-01-08T10:53:05+00:00\",\"description\":\"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici\",\"breadcrumb\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg\",\"contentUrl\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Foto: Ufficio Stampa Bisceglie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.batmagazine.it\/notizie\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#website\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/\",\"name\":\"BATmagazine\",\"description\":\"Notizie Barletta Andria Trani\",\"publisher\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.batmagazine.it\/notizie\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#organization\",\"name\":\"BATmagazine\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2022\/08\/batlogo.png\",\"contentUrl\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2022\/08\/batlogo.png\",\"width\":246,\"height\":96,\"caption\":\"BATmagazine\"},\"image\":{\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BatMagazine\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/f25ee2762381b507b66ff3f592fb3a5c\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-06-alle-16.52.14.png\",\"contentUrl\":\"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-06-alle-16.52.14.png\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/www.batmagazine.it\/notizie\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine","description":"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/","og_locale":"it_IT","og_type":"article","og_title":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine","og_description":"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici","og_url":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/","og_site_name":"BATmagazine","article_publisher":"https:\/\/www.facebook.com\/BatMagazine","article_published_time":"2024-01-08T10:53:03+00:00","article_modified_time":"2024-01-08T10:53:05+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#article","isPartOf":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/"},"author":{"name":"Redazione","@id":"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/f25ee2762381b507b66ff3f592fb3a5c"},"headline":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola","datePublished":"2024-01-08T10:53:03+00:00","dateModified":"2024-01-08T10:53:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/"},"wordCount":718,"publisher":{"@id":"https:\/\/www.batmagazine.it\/notizie\/#organization"},"image":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg","keywords":["3^ giornata ritorno","Bisceglie Calcio","Eccellenza","Girone A","mister di meo","spinazzola","Stadio Vicino","stagione 2023\/2024"],"articleSection":["Bisceglie","Calcio","Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/","url":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/","name":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola - BATmagazine","isPartOf":{"@id":"https:\/\/www.batmagazine.it\/notizie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage"},"image":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg","datePublished":"2024-01-08T10:53:03+00:00","dateModified":"2024-01-08T10:53:05+00:00","description":"Sesta vittoria di fila per i ragazzi di Pino Di Meo, che sbancano il \u201cVicino\u201d con una prova di carattere e lucidit\u00e0 nei momenti topici","breadcrumb":{"@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#primaryimage","url":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg","contentUrl":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2024\/01\/stefanini-gol-1.jpg","width":2560,"height":1706,"caption":"Foto: Ufficio Stampa Bisceglie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.batmagazine.it\/notizie\/2024\/01\/08\/calcio-eccellenza-la-capolista-bisceglie-riparte-con-un-rotondo-tris-in-casa-dello-spinazzola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.batmagazine.it\/notizie\/"},{"@type":"ListItem","position":2,"name":"Calcio &#8211; Eccellenza, la capolista Bisceglie riparte con un rotondo tris in casa dello Spinazzola"}]},{"@type":"WebSite","@id":"https:\/\/www.batmagazine.it\/notizie\/#website","url":"https:\/\/www.batmagazine.it\/notizie\/","name":"BATmagazine","description":"Notizie Barletta Andria Trani","publisher":{"@id":"https:\/\/www.batmagazine.it\/notizie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.batmagazine.it\/notizie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.batmagazine.it\/notizie\/#organization","name":"BATmagazine","url":"https:\/\/www.batmagazine.it\/notizie\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/logo\/image\/","url":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2022\/08\/batlogo.png","contentUrl":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2022\/08\/batlogo.png","width":246,"height":96,"caption":"BATmagazine"},"image":{"@id":"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BatMagazine"]},{"@type":"Person","@id":"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/f25ee2762381b507b66ff3f592fb3a5c","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.batmagazine.it\/notizie\/#\/schema\/person\/image\/","url":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-06-alle-16.52.14.png","contentUrl":"https:\/\/www.batmagazine.it\/notizie\/wp-content\/uploads\/2020\/07\/Schermata-2020-07-06-alle-16.52.14.png","caption":"Redazione"},"url":"https:\/\/www.batmagazine.it\/notizie\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/posts\/158260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/comments?post=158260"}],"version-history":[{"count":2,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/posts\/158260\/revisions"}],"predecessor-version":[{"id":158265,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/posts\/158260\/revisions\/158265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/media\/158261"}],"wp:attachment":[{"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/media?parent=158260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/categories?post=158260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.batmagazine.it\/notizie\/wp-json\/wp\/v2\/tags?post=158260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}